{"id":2506,"date":"2012-06-01T01:35:33","date_gmt":"2012-05-31T23:35:33","guid":{"rendered":"http:\/\/www.dissonanzstudien.de\/blog\/?p=2506"},"modified":"2012-06-01T02:07:08","modified_gmt":"2012-06-01T00:07:08","slug":"bilanz-august-2011-mai-2011","status":"publish","type":"post","link":"https:\/\/www.dissonanzstudien.de\/blog\/2012\/06\/01\/bilanz-august-2011-mai-2011\/","title":{"rendered":"bilanz august 2011 &#8211; mai 2012"},"content":{"rendered":"<p>da gibt es doch einiges nachzuholen f\u00fcr die damen und herren analysten. besuche jeweils auf der ausgangsseite betrachtet.<\/p>\n<p>08\/2011: 10.045 = 324 pro tag<br \/>\n09\/2011: 10.012 = 334 pro tag<br \/>\n10\/2011: 9.942 = 320 pro tag<br \/>\n11\/2011: 10.315 = 344 pro tag<br \/>\n12\/2011: 11.292 = 364 pro tag<br \/>\n01\/2012: 9.608 = 309 pro tag<br \/>\n02\/2012: 7.222 = 257 pro tag<br \/>\n03\/2012: 8.073 = 260 pro tag<br \/>\n04\/2012: 8.825 = 294 pro tag<br \/>\n05\/2012: 8.667 = 279 pro tag<\/p>\n<p>korrespondiert irgendwie so gar nicht mit der posting-anzahl, andererseits mache ich mir auch wenige gedanken dar\u00fcber und freue mich nach wie vor \u00fcber jeden &#8211; daher nat\u00fcrlich vielen dank an die interessenten, neue und alte.<\/p>\n<p>was ist so unter der haube seit der letzten bilanz passiert?<br \/>\ndie wordpress-version ist einigerma\u00dfen aktuell (3.3.1). m\u00f6glich machte dies ein php- und mysql-update, so dass die aktualisierungsprozedur ohne blessuren \u00fcber die b\u00fchne gehen konnte (danke nochmal an <a href=\"http:\/\/www.sprachrestprodukte.de\/\">lame<\/a>, den prozess in gang zu setzen).<br \/>\nsuffusion hat sich meiner meinung nach als theme bew\u00e4hrt. da ich dies seinerzeit f\u00fcr <a href=\"http:\/\/antispambee.de\/\">antispam bee<\/a> implementiert hatte, sogar in doppelter hinsicht: das plugin hat seit anfang m\u00e4rz nach aktuellem stand 825 spam-kommentare geblockt. in der zeit musste ich nur einen kommentar manuell markieren. das alleine zeigt schon, dass sergej m\u00fcller hervorragende arbeit damit geleistet hat. das mail-aufkommen ist also drastisch reduziert.<br \/>\nvorgestern habe ich den audio player durch <a href=\"http:\/\/wordpress.org\/extend\/plugins\/wpaudio-mp3-player\/\">wpaudio<\/a> ersetzt. der ist zwar wesentlich simpler (zum beispiel fehlt die steuerung f\u00fcr die lautst\u00e4rke), setzt jedoch auf html5 statt flash und bietet neben skipping im jeweiligen mix auch eine wesentlich einfachere m\u00f6glichkeit, sich die mp3s herunterladen zu k\u00f6nnen &#8211; sprich: der download-link befindet sich jetzt unten rechts, sobald ihr die wiedergabe startet.<\/p>\n<p>damit zu den pl\u00e4nen, bzw. der to-do-liste:<\/p>\n<ul>\n<li>die kindle-kompatible version meiner master-arbeit fertigstellen (nein, ist nicht vergessen, es fehlt nur die zeit).<\/li>\n<\/ul>\n<ul>\n<li>eine page anlegen, in der meine gesammelten werke \/ mixe fein s\u00e4uberlich nach jahren geordnet auftauchen. ist nach meinem daf\u00fcrhalten eine ganz gute gelegenheit, die stilistische und technische entwicklung nachvollziehen zu k\u00f6nnen.<\/li>\n<\/ul>\n<p>ansonsten direkt gefragt: kommt ihr mit der zur\u00fcckverlagerung der partyberichte in die kommentare als quasi live-berichterstattung klar oder h\u00e4ttet ihr das lieber wie vorher? mir erleichtert das die sache enorm, da sich eintr\u00e4ge auf dem smartphone nicht so toll bearbeiten lassen und es \u00fcber die kommentare weitaus schneller geht.<\/p>\n<p>charts &#8211; nun ja, gen\u00fcgend musik habe ich definitiv gekauft, daher w\u00fcrde es f\u00fcr mehr als eine top 10 reichen. andererseits fehlt mir da etwas der \u00fcberblick. wenn ich die boomkat- und bleep-eink\u00e4ufe mal durchgehe, kann ich bestimmt die einkaufslisten rekonstruieren, insofern gibt es hier meine 10 favorisierten android-apps f\u00fcr unterwegs:<\/p>\n<p>01. \u00f6ffi<br \/>\n02. opera mobile<br \/>\n03. google maps<br \/>\n04. google mail<br \/>\n05. k9-mail<br \/>\n06. wikipedia<br \/>\n07. tagesschau<br \/>\n08. whatsapp<br \/>\n09. drivenow<br \/>\n10. wetter.com<\/p>\n<p>nochmal: vielen dank, bleibt mir gewogen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da gibt es doch einiges nachzuholen f\u00fcr die damen und herren analysten. besuche jeweils auf der ausgangsseite betrachtet. 08\/2011: 10.045 = 324 pro tag 09\/2011: 10.012 = 334 pro tag 10\/2011: 9.942 = 320 pro tag 11\/2011: 10.315 = 344 pro tag 12\/2011: 11.292 = 364 pro tag 01\/2012: 9.608 = 309 pro tag 02\/2012:&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2506","post","type-post","status-publish","format-standard","hentry","category-interna"],"modified_by":"stype","_links":{"self":[{"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/posts\/2506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/comments?post=2506"}],"version-history":[{"count":6,"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/posts\/2506\/revisions"}],"predecessor-version":[{"id":2514,"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/posts\/2506\/revisions\/2514"}],"wp:attachment":[{"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/media?parent=2506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/categories?post=2506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dissonanzstudien.de\/blog\/wp-json\/wp\/v2\/tags?post=2506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}